{"id":27693,"date":"2020-02-13T16:23:13","date_gmt":"2020-02-13T16:23:13","guid":{"rendered":"https:\/\/kopie.dst.deutsche-schule.eu\/?p=27693"},"modified":"2020-02-17T15:09:53","modified_gmt":"2020-02-17T15:09:53","slug":"un0o-dos-o-tres-2020","status":"publish","type":"post","link":"https:\/\/www.dstenerife.eu\/es\/un0o-dos-o-tres-2020\/","title":{"rendered":"Uno, Dos o Tres 2020"},"content":{"rendered":"<p>UNO DOS O TRES&#8230;<\/p>\n<p>\u00a1Ya estamos ah\u00ed!<\/p>\n<p>Ha llegado febrero. 3 alumnos de 4\u00b0 de Primaria viajan a M\u00fanich a la grabaci\u00f3n del concurso<br \/>\n\u00ab1,2 oder 3\u00bb.<\/p>\n<p>Estos\u00a0alumnos fueron elegidos por sus compa\u00f1eros:<\/p>\n<p>Pablo Molina Garz\u00f3n<\/p>\n<p>Daniela G\u00f3mez Ocete<\/p>\n<p>Carlota\u00a0Rodr\u00edguez Ardura<\/p>\n<p>En verano de 2020 se emitir\u00e1 el programa en ZDF y KIGA.<\/p>\n<p>En este momento abrimos el diario y la <style>.modula-best-grid-gallery .modula-fancybox-container.modula-lightbox-jtg-link-33308 {--fancybox-bg:rgba(30,30,30,0.9);--fancybox-opacity:1 !important;}.modula-fancybox-container.modula-lightbox-jtg-link-33308 .modula-fancybox-caption .modula-fancybox-caption__body, .modula-fancybox-container.modula-lightbox-jtg-link-33308 .modula-fancybox-caption .modula-fancybox-caption__body p {text-align:center}.modula-fancybox-container.modula-lightbox-jtg-link-33308 .fancybox__caption {align-self:center}<\/style><a id=\"jtg-link-33308\" data-images=\"[{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_1.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_1.jpg?strip=all&amp;resize=120%2C67&quot;,&quot;image_id&quot;:&quot;27705&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_2.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_2.jpg?strip=all&amp;resize=120%2C90&quot;,&quot;image_id&quot;:&quot;27738&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_3.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_3.jpg?strip=all&amp;resize=120%2C67&quot;,&quot;image_id&quot;:&quot;27740&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_4.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_4.jpg?strip=all&amp;resize=68%2C120&quot;,&quot;image_id&quot;:&quot;27742&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0010.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0010.jpg?strip=all&amp;resize=120%2C67&quot;,&quot;image_id&quot;:&quot;27744&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0023.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0023.jpg?strip=all&amp;resize=90%2C120&quot;,&quot;image_id&quot;:&quot;27746&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0013.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0013.jpg?strip=all&amp;resize=120%2C67&quot;,&quot;image_id&quot;:&quot;27748&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0015.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0015.jpg?strip=all&amp;resize=90%2C120&quot;,&quot;image_id&quot;:&quot;27750&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0020.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0020.jpg?strip=all&amp;resize=90%2C120&quot;,&quot;image_id&quot;:&quot;27752&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0021.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0021.jpg?strip=all&amp;resize=68%2C120&quot;,&quot;image_id&quot;:&quot;27754&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0022.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0022.jpg?strip=all&amp;resize=90%2C120&quot;,&quot;image_id&quot;:&quot;27756&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0011.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200214-WA0011.jpg?strip=all&amp;resize=120%2C67&quot;,&quot;image_id&quot;:&quot;27758&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0021.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0021.jpg?strip=all&amp;resize=90%2C120&quot;,&quot;image_id&quot;:&quot;27783&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0020.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0020.jpg?strip=all&amp;resize=120%2C90&quot;,&quot;image_id&quot;:&quot;27785&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0019.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0019.jpg?strip=all&amp;resize=120%2C90&quot;,&quot;image_id&quot;:&quot;27787&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0025.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0025.jpg?strip=all&amp;resize=120%2C67&quot;,&quot;image_id&quot;:&quot;27789&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0022.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0022.jpg?strip=all&amp;resize=90%2C120&quot;,&quot;image_id&quot;:&quot;27791&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0023.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0023.jpg?strip=all&amp;resize=120%2C90&quot;,&quot;image_id&quot;:&quot;27793&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200216-WA0006.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200216-WA0006.jpg?strip=all&amp;resize=68%2C120&quot;,&quot;image_id&quot;:&quot;27795&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0024.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200215-WA0024.jpg?strip=all&amp;resize=120%2C90&quot;,&quot;image_id&quot;:&quot;27797&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200216-WA0007-e1581865921496.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/IMG-20200216-WA0007-e1581865921496.jpg?strip=all&amp;resize=120%2C67&quot;,&quot;image_id&quot;:&quot;27799&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_4-1.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_4-1.jpg?strip=all&amp;resize=68%2C120&quot;,&quot;image_id&quot;:&quot;27806&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_5.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_5.jpg?strip=all&amp;resize=90%2C120&quot;,&quot;image_id&quot;:&quot;27808&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_6.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_6.jpg?strip=all&amp;resize=120%2C90&quot;,&quot;image_id&quot;:&quot;27810&quot;}},{&quot;src&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_7.jpg?strip=all&quot;,&quot;opts&quot;:{&quot;caption&quot;:&quot;&lt;p&gt;  &lt;\\\/p&gt; &quot;,&quot;thumb&quot;:&quot;https:\\\/\\\/e969z83yjsq.exactdn.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/123_7.jpg?strip=all&amp;resize=90%2C120&quot;,&quot;image_id&quot;:&quot;27812&quot;}}]\" data-config=\"{&quot;lightbox&quot;:&quot;true&quot;,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;],&quot;left&quot;:[&quot;infobar&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false,&quot;transition&quot;:&quot;fade&quot;},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:&quot;next&quot;,&quot;PageDown&quot;:&quot;prev&quot;,&quot;ArrowUp&quot;:&quot;prev&quot;,&quot;ArrowDown&quot;:&quot;next&quot;,&quot;ArrowRight&quot;:&quot;next&quot;,&quot;ArrowLeft&quot;:&quot;prev&quot;},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Cerrar&quot;,&quot;NEXT&quot;:&quot;Siguiente&quot;,&quot;PREV&quot;:&quot;Anterior&quot;,&quot;Error&quot;:&quot;No se ha podido cargar el contenido solicitado. Por favor, int\\u00e9ntalo de nuevo m\\u00e1s tarde.&quot;,&quot;PLAY_START&quot;:&quot;Empezar la presentaci\\u00f3n&quot;,&quot;PLAY_STOP&quot;:&quot;Pausar la presentaci\\u00f3n&quot;,&quot;FULL_SCREEN&quot;:&quot;Pantalla completa&quot;,&quot;THUMBS&quot;:&quot;Miniaturas&quot;,&quot;DOWNLOAD&quot;:&quot;Descargar&quot;,&quot;SHARE&quot;:&quot;Compartir&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;Puedes cerrar este contenido emergente con la tecla ESC&quot;,&quot;ERROR&quot;:&quot;Algo ha ido mal, pro favor, prueba de nuevo m\\u00e1s tarde&quot;,&quot;IMAGE_ERROR&quot;:&quot;Imagen no encontrada&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;No se ha encontrado el elemento HTML&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error al cargar AJAX: No encontrado&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error al cargar AJAX: Prohibido&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error al cargar la p\\u00e1gina&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Alternar nivel de ampliar\\\/acercar&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Alternar miniaturas&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Alternar diapositiva&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Cambiar al modo de pantalla completa&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2},&quot;zoom&quot;:false},&quot;toolbar&quot;:true,&quot;wheel&quot;:false,&quot;animationEffect&quot;:&quot;&quot;,&quot;transitionEffect&quot;:&quot;fade&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video modula_html5_video\\&quot; controls playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;,&quot;vimeo&quot;:{&quot;autopause&quot;:0}},&quot;Fullscreen&quot;:{&quot;autoStart&quot;:true},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-link-33308&quot;,&quot;showClass&quot;:&quot;m-In&quot;,&quot;hideClass&quot;:&quot;m-Out&quot;},&quot;options&quot;:{&quot;enableSlideshow&quot;:0,&quot;enableAutoplay&quot;:&quot;0&quot;,&quot;slideshowSpeed&quot;:5000,&quot;pauseOnHover&quot;:&quot;0&quot;}}\" class=\"jtg-33308 modula-link\" href=\"#\">galer\u00eda de fotos<\/a>.<\/p>\n<p><strong>Jueves,\u00a013.02.2020<\/strong><\/p>\n<p style=\"text-align: justify;\">Nosotros (Daniela, Pablo y Carlota de las clases 4) hemos volado a M\u00fanich con Marion Lehrmann. Aqu\u00ed participaremos en el concurso infantil de la televisi\u00f3n alemana.<\/p>\n<p style=\"text-align: justify;\">Ayer conocimos a otros candidatos de Alemania, que nos hicieron varias recomendaciones.<\/p>\n<p style=\"text-align: justify;\"><strong>S\u00e1bado, 15.02.2020<\/strong><\/p>\n<p style=\"text-align: justify;\">Hoy tuvimos un programa completo: primero fuimos al zoo, donde vimos elefantes, jirafas y muchos animales que no existen en Tenerife&#8230;<\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n fuimos a un concierto de m\u00fasica cl\u00e1sica para ni\u00f1os. \u00a1Estuvo genial!<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n fuimos al cine&#8230; un d\u00eda agotador, pero muy divertido.<\/p>\n<p style=\"text-align: justify;\"><strong>Domingo, 16.02.2020<\/strong><\/p>\n<p>Esta ma\u00f1ana fuimos a los estudios de cine Bavaria y hemos visto c\u00f3mo se hacen las pel\u00edculas.<\/p>\n<p><strong>Lunes, 17.02.2020<\/strong><\/p>\n<p>\u00a1Hoy ganamos el primer premio en el concurso \u00ab1, 2 o 3\u00bb! El tema era diversi\u00f3n-deportes acu\u00e1ticos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div  id=\"jtg-33308\" class=\"modula modula-gallery modula-creative-gallery\" data-config=\"{&quot;height&quot;:800,&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;creative-gallery&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:&quot;0&quot;,&quot;tabletColumns&quot;:&quot;2&quot;,&quot;mobileColumns&quot;:&quot;1&quot;,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;],&quot;left&quot;:[&quot;infobar&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false,&quot;transition&quot;:&quot;fade&quot;},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:&quot;next&quot;,&quot;PageDown&quot;:&quot;prev&quot;,&quot;ArrowUp&quot;:&quot;prev&quot;,&quot;ArrowDown&quot;:&quot;next&quot;,&quot;ArrowRight&quot;:&quot;next&quot;,&quot;ArrowLeft&quot;:&quot;prev&quot;},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Cerrar&quot;,&quot;NEXT&quot;:&quot;Siguiente&quot;,&quot;PREV&quot;:&quot;Anterior&quot;,&quot;Error&quot;:&quot;No se ha podido cargar el contenido solicitado. Por favor, int\\u00e9ntalo de nuevo m\\u00e1s tarde.&quot;,&quot;PLAY_START&quot;:&quot;Empezar la presentaci\\u00f3n&quot;,&quot;PLAY_STOP&quot;:&quot;Pausar la presentaci\\u00f3n&quot;,&quot;FULL_SCREEN&quot;:&quot;Pantalla completa&quot;,&quot;THUMBS&quot;:&quot;Miniaturas&quot;,&quot;DOWNLOAD&quot;:&quot;Descargar&quot;,&quot;SHARE&quot;:&quot;Compartir&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;Puedes cerrar este contenido emergente con la tecla ESC&quot;,&quot;ERROR&quot;:&quot;Algo ha ido mal, pro favor, prueba de nuevo m\\u00e1s tarde&quot;,&quot;IMAGE_ERROR&quot;:&quot;Imagen no encontrada&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;No se ha encontrado el elemento HTML&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error al cargar AJAX: No encontrado&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error al cargar AJAX: Prohibido&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error al cargar la p\\u00e1gina&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Alternar nivel de ampliar\\\/acercar&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Alternar miniaturas&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Alternar diapositiva&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Cambiar al modo de pantalla completa&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2},&quot;zoom&quot;:false},&quot;toolbar&quot;:true,&quot;wheel&quot;:false,&quot;animationEffect&quot;:&quot;&quot;,&quot;transitionEffect&quot;:&quot;fade&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video modula_html5_video\\&quot; controls playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;,&quot;vimeo&quot;:{&quot;autopause&quot;:0}},&quot;Fullscreen&quot;:{&quot;autoStart&quot;:true},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-33308&quot;,&quot;showClass&quot;:&quot;m-In&quot;,&quot;hideClass&quot;:&quot;m-Out&quot;},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;,&quot;filterClick&quot;:&quot;0&quot;,&quot;dropdownFilters&quot;:&quot;0&quot;,&quot;defaultActiveFilter&quot;:&quot;all&quot;,&quot;initLightbox&quot;:&quot;modula_pro_init_lightbox&quot;,&quot;haveFilters&quot;:0,&quot;lightbox_devices&quot;:&quot;both&quot;,&quot;options&quot;:{&quot;lightbox&quot;:&quot;fancybox&quot;},&quot;enableSlideshow&quot;:0,&quot;enableAutoplay&quot;:&quot;0&quot;,&quot;slideshowSpeed&quot;:5000,&quot;pauseOnHover&quot;:&quot;0&quot;}\">\n\n\t\n\t<div  class=\"modula-items\">\n\t\t<div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27705\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1-640x360.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img fetchpriority=\"high\" decoding=\"async\" class=\"pic wp-image-27705\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/123_1.jpg\" title=\"123_1\" crop=\"\" width=\"640\" height=\"360\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1-640x360.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1-640x360.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1-640x360.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1-1140x641.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1-180x101.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1-768x432.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1-1536x864.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1-533x300.jpg?strip=all 533w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_1.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27738\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2.jpg?strip=all&amp;fit=564%2C423\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-27738\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/123_2.jpg\" title=\"123_2\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2.jpg?strip=all&amp;fit=564%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2.jpg?strip=all&amp;fit=564%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2-640x480.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2-1140x855.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2-180x135.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2-400x300.jpg?strip=all 400w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_2.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27740\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3-640x360.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-27740\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/123_3.jpg\" title=\"123_3\" crop=\"\" width=\"640\" height=\"360\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3-640x360.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3-640x360.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3-640x360.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3-1140x641.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3-180x101.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3-768x432.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3-1536x864.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3-533x300.jpg?strip=all 533w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_3.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27742\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4.jpg?strip=all&amp;fit=238%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27742\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/123_4.jpg\" title=\"123_4\" crop=\"\" width=\"238\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4.jpg?strip=all&amp;fit=238%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4.jpg?strip=all&amp;fit=238%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4.jpg?strip=all 900w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-640x1138.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-180x320.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-768x1365.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-864x1536.jpg?strip=all 864w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-169x300.jpg?strip=all 169w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4.jpg?strip=all&amp;w=360 360w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4.jpg?strip=all&amp;w=540 540w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27744\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010-640x360.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27744\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010.jpg\" title=\"IMG-20200214-WA0010\" crop=\"\" width=\"640\" height=\"360\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010-640x360.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010-640x360.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010-640x360.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010-1140x641.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010-180x101.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010-768x432.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010-1536x864.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010-533x300.jpg?strip=all 533w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0010.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27746\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023.jpg?strip=all&amp;fit=317%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27746\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023.jpg\" title=\"IMG-20200214-WA0023\" crop=\"\" width=\"317\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023.jpg?strip=all&amp;fit=317%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023.jpg?strip=all&amp;fit=317%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023.jpg?strip=all 1200w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023-640x853.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023-1140x1520.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023-180x240.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023-768x1024.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023-1152x1536.jpg?strip=all 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023-225x300.jpg?strip=all 225w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023.jpg?strip=all&amp;w=480 480w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0023.jpg?strip=all&amp;w=960 960w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27748\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013-640x360.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27748\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013.jpg\" title=\"IMG-20200214-WA0013\" crop=\"\" width=\"640\" height=\"360\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013-640x360.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013-640x360.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013-640x360.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013-1140x641.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013-180x101.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013-768x432.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013-1536x864.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013-533x300.jpg?strip=all 533w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0013.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27750\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015.jpg?strip=all&amp;fit=317%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27750\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015.jpg\" title=\"IMG-20200214-WA0015\" crop=\"\" width=\"317\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015.jpg?strip=all&amp;fit=317%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015.jpg?strip=all&amp;fit=317%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015.jpg?strip=all 1200w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015-640x853.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015-1140x1520.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015-180x240.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015-768x1024.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015-1152x1536.jpg?strip=all 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015-225x300.jpg?strip=all 225w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015.jpg?strip=all&amp;w=480 480w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0015.jpg?strip=all&amp;w=960 960w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27752\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020.jpg?strip=all&amp;fit=317%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27752\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020.jpg\" title=\"IMG-20200214-WA0020\" crop=\"\" width=\"317\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020.jpg?strip=all&amp;fit=317%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020.jpg?strip=all&amp;fit=317%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020.jpg?strip=all 1200w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020-640x853.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020-1140x1520.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020-180x240.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020-768x1024.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020-1152x1536.jpg?strip=all 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020-225x300.jpg?strip=all 225w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020.jpg?strip=all&amp;w=480 480w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0020.jpg?strip=all&amp;w=960 960w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27754\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021.jpg?strip=all&amp;fit=238%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27754\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021.jpg\" title=\"IMG-20200214-WA0021\" crop=\"\" width=\"238\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021.jpg?strip=all&amp;fit=238%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021.jpg?strip=all&amp;fit=238%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021.jpg?strip=all 900w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021-640x1138.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021-180x320.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021-768x1365.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021-864x1536.jpg?strip=all 864w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021-169x300.jpg?strip=all 169w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021.jpg?strip=all&amp;w=360 360w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0021.jpg?strip=all&amp;w=540 540w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27756\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022.jpg?strip=all&amp;fit=317%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27756\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022.jpg\" title=\"IMG-20200214-WA0022\" crop=\"\" width=\"317\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022.jpg?strip=all&amp;fit=317%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022.jpg?strip=all&amp;fit=317%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022.jpg?strip=all 1200w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022-640x853.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022-1140x1520.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022-180x240.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022-768x1024.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022-1152x1536.jpg?strip=all 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022-225x300.jpg?strip=all 225w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022.jpg?strip=all&amp;w=480 480w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0022.jpg?strip=all&amp;w=960 960w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27758\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011-640x360.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27758\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011.jpg\" title=\"IMG-20200214-WA0011\" crop=\"\" width=\"640\" height=\"360\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011-640x360.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011-640x360.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011-640x360.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011-1140x641.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011-180x101.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011-768x432.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011-1536x864.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011-533x300.jpg?strip=all 533w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200214-WA0011.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27783\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021.jpg?strip=all&amp;fit=317%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27783\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021.jpg\" title=\"IMG-20200215-WA0021\" crop=\"\" width=\"317\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021.jpg?strip=all&amp;fit=317%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021.jpg?strip=all&amp;fit=317%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021.jpg?strip=all 1200w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021-640x853.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021-1140x1520.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021-180x240.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021-768x1024.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021-1152x1536.jpg?strip=all 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021-225x300.jpg?strip=all 225w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021.jpg?strip=all&amp;w=480 480w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0021.jpg?strip=all&amp;w=960 960w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27785\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020.jpg?strip=all&amp;fit=564%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27785\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020.jpg\" title=\"IMG-20200215-WA0020\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020.jpg?strip=all&amp;fit=564%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020.jpg?strip=all&amp;fit=564%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020-640x480.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020-1140x855.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020-180x135.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020-400x300.jpg?strip=all 400w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0020.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27787\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019.jpg?strip=all&amp;fit=564%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27787\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019.jpg\" title=\"IMG-20200215-WA0019\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019.jpg?strip=all&amp;fit=564%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019.jpg?strip=all&amp;fit=564%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019-640x480.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019-1140x855.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019-180x135.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019-400x300.jpg?strip=all 400w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0019.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27789\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025-640x360.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27789\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025.jpg\" title=\"IMG-20200215-WA0025\" crop=\"\" width=\"640\" height=\"360\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025-640x360.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025-640x360.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025-640x360.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025-1140x641.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025-180x101.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025-768x432.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025-1536x864.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025-533x300.jpg?strip=all 533w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0025.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27791\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022.jpg?strip=all&amp;fit=317%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27791\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022.jpg\" title=\"IMG-20200215-WA0022\" crop=\"\" width=\"317\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022.jpg?strip=all&amp;fit=317%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022.jpg?strip=all&amp;fit=317%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022.jpg?strip=all 1200w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022-640x853.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022-1140x1520.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022-180x240.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022-768x1024.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022-1152x1536.jpg?strip=all 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022-225x300.jpg?strip=all 225w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022.jpg?strip=all&amp;w=480 480w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0022.jpg?strip=all&amp;w=960 960w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27793\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023.jpg?strip=all&amp;fit=564%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27793\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023.jpg\" title=\"IMG-20200215-WA0023\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023.jpg?strip=all&amp;fit=564%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023.jpg?strip=all&amp;fit=564%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023-640x480.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023-1140x855.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023-180x135.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023-400x300.jpg?strip=all 400w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0023.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27795\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006.jpg?strip=all&amp;fit=238%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27795\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006.jpg\" title=\"IMG-20200216-WA0006\" crop=\"\" width=\"238\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006.jpg?strip=all&amp;fit=238%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006.jpg?strip=all&amp;fit=238%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006.jpg?strip=all 900w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006-640x1138.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006-180x320.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006-768x1365.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006-864x1536.jpg?strip=all 864w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006-169x300.jpg?strip=all 169w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006.jpg?strip=all&amp;w=360 360w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0006.jpg?strip=all&amp;w=540 540w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27797\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024.jpg?strip=all&amp;fit=564%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27797\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024.jpg\" title=\"IMG-20200215-WA0024\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024.jpg?strip=all&amp;fit=564%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024.jpg?strip=all&amp;fit=564%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024-640x480.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024-1140x855.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024-180x135.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024-400x300.jpg?strip=all 400w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200215-WA0024.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27799\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496-640x360.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27799\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496.jpg\" title=\"IMG-20200216-WA0007\" crop=\"\" width=\"640\" height=\"360\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496-640x360.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496-640x360.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496-640x360.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496-1140x641.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496-180x101.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496-768x432.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496-1536x864.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496-533x300.jpg?strip=all 533w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/IMG-20200216-WA0007-e1581865921496.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27806\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1.jpg?strip=all&amp;fit=238%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27806\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/123_4-1.jpg\" title=\"123_4\" crop=\"\" width=\"238\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1.jpg?strip=all&amp;fit=238%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1.jpg?strip=all&amp;fit=238%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1.jpg?strip=all 900w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1-640x1138.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1-180x320.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1-768x1365.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1-864x1536.jpg?strip=all 864w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1-169x300.jpg?strip=all 169w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1.jpg?strip=all&amp;w=360 360w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_4-1.jpg?strip=all&amp;w=540 540w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27808\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5.jpg?strip=all&amp;fit=317%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27808\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/123_5.jpg\" title=\"123_5\" crop=\"\" width=\"317\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5.jpg?strip=all&amp;fit=317%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5.jpg?strip=all&amp;fit=317%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5.jpg?strip=all 1200w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5-640x853.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5-1140x1520.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5-180x240.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5-768x1024.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5-1152x1536.jpg?strip=all 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5-225x300.jpg?strip=all 225w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5.jpg?strip=all&amp;w=480 480w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_5.jpg?strip=all&amp;w=960 960w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27810\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6.jpg?strip=all&amp;fit=564%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27810\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/123_6.jpg\" title=\"123_6\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6.jpg?strip=all&amp;fit=564%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6.jpg?strip=all&amp;fit=564%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6.jpg?strip=all 1600w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6-640x480.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6-1140x855.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6-180x135.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6-400x300.jpg?strip=all 400w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6.jpg?strip=all&amp;w=320 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6.jpg?strip=all&amp;w=960 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6.jpg?strip=all&amp;w=1280 1280w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_6.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"27812\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-33308\" data-caption=\"&lt;span class=&quot;modula-caption-description&quot;&gt;&lt;\/span&gt;\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7.jpg?strip=all&amp;fit=317%2C423\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-27812\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2020\/02\/123_7.jpg\" title=\"123_7\" crop=\"\" width=\"317\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7.jpg?strip=all&amp;fit=317%2C423\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7.jpg?strip=all&amp;fit=317%2C423\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7.jpg?strip=all 1200w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7-640x853.jpg?strip=all 640w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7-1140x1520.jpg?strip=all 1140w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7-180x240.jpg?strip=all 180w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7-768x1024.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7-1152x1536.jpg?strip=all 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7-225x300.jpg?strip=all 225w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7.jpg?strip=all&amp;w=480 480w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2020\/02\/123_7.jpg?strip=all&amp;w=960 960w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/www.dstenerife.eu\/es\/un0o-dos-o-tres-2020\/#modula-gallery-33308\",\n\t\t\"url\"     : \"https:\/\/www.dstenerife.eu\/es\/un0o-dos-o-tres-2020\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>UNO DOS O TRES&#8230; \u00a1Ya estamos ah\u00ed! Ha llegado febrero. 3 alumnos de 4\u00b0 de Primaria [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":27689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":""},"categories":[28],"tags":[],"schlagwortedst":[],"class_list":["post-27693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio"],"_links":{"self":[{"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/posts\/27693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/comments?post=27693"}],"version-history":[{"count":0,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/posts\/27693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/media\/27689"}],"wp:attachment":[{"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/media?parent=27693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/categories?post=27693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/tags?post=27693"},{"taxonomy":"schlagwortedst","embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/schlagwortedst?post=27693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}