{"id":88401,"date":"2024-12-20T16:32:15","date_gmt":"2024-12-20T16:32:15","guid":{"rendered":"https:\/\/www.dstenerife.eu\/?p=88401"},"modified":"2024-12-20T16:36:20","modified_gmt":"2024-12-20T16:36:20","slug":"adopta-un-abuelo-este-ano-la-navidad-viene-en-un-sobre","status":"publish","type":"post","link":"https:\/\/www.dstenerife.eu\/es\/adopta-un-abuelo-este-ano-la-navidad-viene-en-un-sobre\/","title":{"rendered":"\u00abAdopta Un Abuelo\u00bb &#8211; Este a\u00f1o la Navidad viene en un sobre"},"content":{"rendered":"<p>Como parte del proyecto solidario navide\u00f1o de este a\u00f1o \u00abAdopta Un Abuelo\u00bb, las ni\u00f1as y los ni\u00f1os de nuestro Kindergarten han pintado bonitos dibujos con mucho amor y creatividad, que ahora se est\u00e1n distribuyendo a personas mayores que viven en residencias de ancianos. La iniciativa \u00abAdopta Un Abuelo\u00bb pretende reducir la soledad de las personas mayores y aportarles nuevas alegr\u00edas a trav\u00e9s de las conexiones interpersonales.<\/p>\n<p>Las ni\u00f1as y los ni\u00f1os han acogido este proyecto con entusiasmo y han comprendido la importancia de la campa\u00f1a. Han disfrutado creando sus dibujos para hacer sonre\u00edr a los mayores y hacerles sentir que no est\u00e1n olvidados.<\/p>\n<p>Este proyecto no s\u00f3lo ofrece a las ni\u00f1as y a los ni\u00f1os una magn\u00edfica oportunidad de expresar su creatividad, sino tambi\u00e9n una valiosa experiencia de empat\u00eda y responsabilidad interpersonal. Estamos orgullosos de formar parte de esta gran iniciativa y encantados de que nuestros peque\u00f1os artistas hayan podido contribuir a la solidaridad intergeneracional a trav\u00e9s de sus dibujos.<\/p>\n<p>Esperamos con impaciencia las reacciones de las destinatarias y los destinatarios, estas ser\u00e1n publicadas en las redes sociales de la organiaci\u00f3n.<\/p>\n<div  id=\"jtg-88396\" class=\"modula modula-gallery modula-creative-gallery\" data-config=\"{&quot;height&quot;:550,&quot;tabletHeight&quot;:450,&quot;mobileHeight&quot;:450,&quot;desktopHeight&quot;:550,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;creative-gallery&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:10,&quot;mobileGutter&quot;:10,&quot;tabletGutter&quot;:10,&quot;desktopGutter&quot;:10,&quot;enableResponsive&quot;:&quot;0&quot;,&quot;tabletColumns&quot;:2,&quot;mobileColumns&quot;:1,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false,&quot;position&quot;:&quot;left&quot;},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;zoomIn&quot;,&quot;zoomOut&quot;,&quot;thumbs&quot;,&quot;close&quot;],&quot;left&quot;:[&quot;infobar&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:true,&quot;transition&quot;:&quot;slide&quot;},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:&quot;next&quot;,&quot;PageDown&quot;:&quot;prev&quot;,&quot;ArrowUp&quot;:&quot;prev&quot;,&quot;ArrowDown&quot;:&quot;next&quot;,&quot;ArrowRight&quot;:&quot;next&quot;,&quot;ArrowLeft&quot;:&quot;prev&quot;},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Cerrar&quot;,&quot;NEXT&quot;:&quot;Siguiente&quot;,&quot;PREV&quot;:&quot;Anterior&quot;,&quot;Error&quot;:&quot;No se ha podido cargar el contenido solicitado. Por favor, int\\u00e9ntalo de nuevo m\\u00e1s tarde.&quot;,&quot;PLAY_START&quot;:&quot;Empezar la presentaci\\u00f3n&quot;,&quot;PLAY_STOP&quot;:&quot;Pausar la presentaci\\u00f3n&quot;,&quot;FULL_SCREEN&quot;:&quot;Pantalla completa&quot;,&quot;THUMBS&quot;:&quot;Miniaturas&quot;,&quot;DOWNLOAD&quot;:&quot;Descargar&quot;,&quot;SHARE&quot;:&quot;Compartir&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;Puedes cerrar este contenido emergente con la tecla ESC&quot;,&quot;ERROR&quot;:&quot;Algo ha ido mal, pro favor, prueba de nuevo m\\u00e1s tarde&quot;,&quot;IMAGE_ERROR&quot;:&quot;Imagen no encontrada&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;No se ha encontrado el elemento HTML&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error al cargar AJAX: No encontrado&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error al cargar AJAX: Prohibido&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error al cargar la p\\u00e1gina&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Alternar nivel de ampliar\\\/acercar&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Alternar miniaturas&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Alternar diapositiva&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Cambiar al modo de pantalla completa&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;toolbar&quot;:true,&quot;wheel&quot;:false,&quot;animationEffect&quot;:&quot;false&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video modula_html5_video\\&quot; controls playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;,&quot;vimeo&quot;:{&quot;autopause&quot;:0}},&quot;Fullscreen&quot;:{&quot;autoStart&quot;:true},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-88396&quot;},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;,&quot;filterClick&quot;:&quot;0&quot;,&quot;dropdownFilters&quot;:&quot;0&quot;,&quot;defaultActiveFilter&quot;:&quot;all&quot;,&quot;initLightbox&quot;:&quot;modula_pro_init_lightbox&quot;,&quot;haveFilters&quot;:0,&quot;lightbox_devices&quot;:&quot;both&quot;,&quot;mobileDoubleClick&quot;:1,&quot;options&quot;:{&quot;lightbox&quot;:&quot;fancybox&quot;},&quot;enableSlideshow&quot;:&quot;0&quot;,&quot;enableAutoplay&quot;:&quot;0&quot;,&quot;slideshowSpeed&quot;:5000,&quot;pauseOnHover&quot;:&quot;0&quot;}\">\n\n\t\n\t<div  class=\"modula-items\">\n\t\t<div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"88355\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-88396\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4-317x423.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img fetchpriority=\"high\" decoding=\"async\" class=\"pic wp-image-88355\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4.jpg\" title=\"Adopta-un-Abuelo-4\" crop=\"\" width=\"317\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4-317x423.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4-317x423.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4.jpg?strip=all 1440w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4-317x423.jpg?strip=all 317w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4-540x720.jpg?strip=all 540w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4-768x1024.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4-1152x1536.jpg?strip=all 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4-320x427.jpg?strip=all 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-4.jpg?strip=all&amp;w=864 864w\" sizes=\"(max-width: 317px) 100vw, 317px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"88347\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-88396\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5-564x423.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-88347\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5.jpg\" title=\"Adopta-un-Abuelo-5\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5-564x423.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5-564x423.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5.jpg?strip=all 1920w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5-564x423.jpg?strip=all 564w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5-960x720.jpg?strip=all 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5-320x240.jpg?strip=all 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5.jpg?strip=all&amp;w=384 384w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5.jpg?strip=all&amp;w=1152 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-5.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"88349\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-88396\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7-564x423.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img decoding=\"async\" class=\"pic wp-image-88349\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7.jpg\" title=\"Adopta-un-Abuelo-7\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7-564x423.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7-564x423.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7.jpg?strip=all 1920w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7-564x423.jpg?strip=all 564w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7-960x720.jpg?strip=all 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7-320x240.jpg?strip=all 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7.jpg?strip=all&amp;w=384 384w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7.jpg?strip=all&amp;w=1152 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-7.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"88357\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-88396\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1-337x423.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-88357\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1.jpg\" title=\"Adopta-un-Abuelo-1\" crop=\"\" width=\"337\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1-337x423.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1-337x423.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1.jpg?strip=all 1529w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1-337x423.jpg?strip=all 337w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1-573x720.jpg?strip=all 573w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1-768x964.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1-1223x1536.jpg?strip=all 1223w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1-320x402.jpg?strip=all 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-1.jpg?strip=all&amp;w=917 917w\" sizes=\"(max-width: 337px) 100vw, 337px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"88353\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-88396\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2-238x423.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-88353\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2.jpg\" title=\"Adopta-un-Abuelo-2\" crop=\"\" width=\"238\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2-238x423.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2-238x423.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2.jpg?strip=all 1080w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2-238x423.jpg?strip=all 238w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2-405x720.jpg?strip=all 405w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2-768x1365.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2-864x1536.jpg?strip=all 864w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2-320x569.jpg?strip=all 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-2.jpg?strip=all&amp;w=648 648w\" sizes=\"(max-width: 238px) 100vw, 238px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"88359\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-88396\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3-564x423.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-88359\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3.jpg\" title=\"Adopta-un-Abuelo-3\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3-564x423.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3-564x423.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3.jpg?strip=all 1920w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3-564x423.jpg?strip=all 564w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3-960x720.jpg?strip=all 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3-320x240.jpg?strip=all 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3.jpg?strip=all&amp;w=384 384w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3.jpg?strip=all&amp;w=1152 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-3.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div><div class=\"modula-item effect-pufrobo jtg-filter-all jtg-filter-\" >\n\t<div class=\"modula-item-overlay\"><\/div>\n\n\t<div class=\"modula-item-content\">\n\n\t\t<a data-image-id=\"88351\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-88396\" data-caption=\"\" aria-label=\"Abrir la imagen en una caja de luz\" data-thumb=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6-564x423.jpg?strip=all\" class=\"tile-inner modula-item-link\"><\/a><img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-88351\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.dstenerife.eu\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6.jpg\" title=\"Adopta-un-Abuelo-6\" crop=\"\" width=\"564\" height=\"423\" src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6-564x423.jpg?strip=all\" data-src=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6-564x423.jpg?strip=all\" data-caption=\"\" srcset=\"https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6.jpg?strip=all 1920w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6-564x423.jpg?strip=all 564w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6-960x720.jpg?strip=all 960w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6-768x576.jpg?strip=all 768w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6-1536x1152.jpg?strip=all 1536w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6-320x240.jpg?strip=all 320w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6.jpg?strip=all&amp;w=384 384w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6.jpg?strip=all&amp;w=1152 1152w, https:\/\/e969z83yjsq.exactdn.com\/wp-content\/uploads\/2024\/12\/Adopta-un-Abuelo-6.jpg?strip=all&amp;w=450 450w\" sizes=\"(max-width: 564px) 100vw, 564px\" \/>\n\t\t<div class=\"figc no-description\">\n\t\t\t<div class=\"figc-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/www.dstenerife.eu\/es\/adopta-un-abuelo-este-ano-la-navidad-viene-en-un-sobre\/#modula-gallery-88396\",\n\t\t\"url\"     : \"https:\/\/www.dstenerife.eu\/es\/adopta-un-abuelo-este-ano-la-navidad-viene-en-un-sobre\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Como parte del proyecto solidario navide\u00f1o de este a\u00f1o \u00abAdopta Un Abuelo\u00bb, las ni\u00f1as y los [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":88399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":""},"categories":[28,132],"tags":[],"schlagwortedst":[],"class_list":["post-88401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colegio","category-infantil-es"],"_links":{"self":[{"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/posts\/88401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/comments?post=88401"}],"version-history":[{"count":1,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/posts\/88401\/revisions"}],"predecessor-version":[{"id":88402,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/posts\/88401\/revisions\/88402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/media\/88399"}],"wp:attachment":[{"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/media?parent=88401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/categories?post=88401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/tags?post=88401"},{"taxonomy":"schlagwortedst","embeddable":true,"href":"https:\/\/www.dstenerife.eu\/es\/wp-json\/wp\/v2\/schlagwortedst?post=88401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}